{"id":8244,"date":"2025-01-24T21:21:40","date_gmt":"2025-01-24T19:21:40","guid":{"rendered":"https:\/\/tintenwolf.mrkeks.net\/?page_id=8244"},"modified":"2025-01-24T21:23:27","modified_gmt":"2025-01-24T19:23:27","slug":"studienarbeiten","status":"publish","type":"page","link":"https:\/\/tintenwolf.mrkeks.net\/en\/konsumierbares\/studienarbeiten\/","title":{"rendered":"Studienarbeiten"},"content":{"rendered":"<p>Meine gesammelten Sachtexte gibt es im Eigenverlag auch als gedrucktes Buch. Der Kostenpunkt liegt bei zehn Euro. Hinzu kommen drei Euro f\u00fcr Verpackung und Versand.<\/p>\n<p><strong>Bei Interesse <a title=\"Kontakt\" href=\"https:\/\/tintenwolf.mrkeks.net\/kontakt\/\">schreibt mich einfach an<\/a>.<\/strong><\/p>\n<p><a href=\"https:\/\/tintenwolf.mrkeks.net\/wp-content\/uploads\/2025\/01\/Studienarbeiten_Meas_front.jpg\"  data-fancybox=\"gallery\" rel=\"group-8244\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-2200\" src=\"https:\/\/tintenwolf.mrkeks.net\/wp-content\/uploads\/2025\/01\/Studienarbeiten_Meas_front.jpg\" alt=\"Studienarbeiten_Meas_front\" width=\"300\" \/><\/a><\/p>\n<p><strong>Inhalt:<\/strong><\/p>\n<p>01. Welche Rolle hatte die Stadt f\u00fcr die Frente Sandinista de Liberaci\u00f3n Nacional in der Nikaraguanischen Revolution?<br \/><br \/>02. Wie beeinflusste der Staats-Shint\u00f4 die \u00bbGleichschaltung\u00ab der japanischen Gesellschaft im Imperialen Japan der 30er- und 40er-Jahre des 20. Jahrhunderts?<br \/><br \/>03. Hermann, Siegfried, Dolchsto\u00df \u2013 Die Varusschlacht im politischen Diskurs der Weimarer Republik<br \/><br \/>04. Wir st\u00f6ren gern \u2013 Straszenmusik als Mittel der politischen Kommunikation?<br \/><br \/>05. Stadtguerilla in Lateinamerika und BRD \u2013 \u00dcber die globale Entwicklung einer urbanen Guerilla<br \/><br \/>06. Stepan Bandera an Reichsminister Alfred Rosenberg \u2013 Eine Quellenanalyse<br \/><br \/>07. Pr\u00e4koloniale Geschichte Haitis \u2013 Eine Lerneinheit in vier Modulen<br \/><br \/>08. Was das Verteilen eines Kuchens mit Rekursion zu tun hat \u2013 Entwurf eines Lernmaterials<br \/><br \/>09. Gender ist wandelbar \u2013 Zur Diversity im Geschichtsunterricht<br \/><br \/>10. Die Aufst\u00e4nde von Kronstadt (1921) und Barcelona (1937) in der Rezeption von Marxist*innen und Anarchist*innen<br \/><br \/>11. Der Libert\u00e4re Kommunalismus. Marxismus oder utopischer Sozialismus?<br \/><br \/>12. R\u00e4tedemokratie und Sozialismus: Das Beispiel Kuba. Ein Artikel re:volt magazine<br \/><br \/>13. Der Dualismus. Grundprinzip von Elementarsystemen &#038; Magietheorien. Ein Fantasy-Sachtext<\/p>\n<p><a title=\"zur\u00fcck\" href=\"https:\/\/tintenwolf.mrkeks.net\/konsumierbares\/\">zur\u00fcck<\/a><\/p>\n\n\n<p><\/p>\n<div class=\"twoclick_social_bookmarks_post_8244 social_share_privacy clearfix 1.6.4 locale-en_GB sprite-de_DE\"><\/div><div class=\"twoclick-js\"><script type=\"text\/javascript\">\/* <![CDATA[ *\/\njQuery(document).ready(function($){if($('.twoclick_social_bookmarks_post_8244')){$('.twoclick_social_bookmarks_post_8244').socialSharePrivacy({\"services\":{\"facebook\":{\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Facebook senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"action\":\"recommend\",\"language\":\"de_DE\"},\"twitter\":{\"reply_to\":\"\",\"tweet_text\":\"Studienarbeiten%20%C2%BB%20Tintenwolf\",\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Twitter senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"language\":\"de\",\"referrer_track\":\"\"},\"gplus\":{\"status\":\"on\",\"txt_info\":\"2 Klicks f\\u00fcr mehr Datenschutz: Erst wenn Sie hier klicken, wird der Button aktiv und Sie k\\u00f6nnen Ihre Empfehlung an Google+ senden. Schon beim Aktivieren werden Daten an Dritte \\u00fcbertragen - siehe <em>i<\\\/em>.\",\"perma_option\":\"off\",\"referrer_track\":\"\"}},\"txt_help\":\"Wenn Sie diese Felder durch einen Klick aktivieren, werden Informationen an Facebook, Twitter, Flattr, Xing, t3n, LinkedIn, Pinterest oder Google eventuell ins Ausland \\u00fcbertragen und unter Umst\\u00e4nden auch dort gespeichert. N\\u00e4heres erfahren Sie durch einen Klick auf das <em>i<\\\/em>.\",\"settings_perma\":\"Dauerhaft aktivieren und Daten\\u00fcber-tragung zustimmen:\",\"info_link\":\"http:\\\/\\\/www.heise.de\\\/ct\\\/artikel\\\/2-Klicks-fuer-mehr-Datenschutz-1333879.html\",\"uri\":\"https:\\\/\\\/tintenwolf.mrkeks.net\\\/en\\\/konsumierbares\\\/studienarbeiten\\\/\",\"post_id\":8244,\"post_title_referrer_track\":\"Studienarbeiten\",\"display_infobox\":\"off\"});}});\n\/* ]]> *\/<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>Meine gesammelten Sachtexte gibt es im Eigenverlag auch als gedrucktes Buch. Der Kostenpunkt liegt bei zehn Euro. Hinzu kommen drei Euro f\u00fcr Verpackung und Versand. Bei Interesse schreibt mich einfach<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":1425,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8244","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/pages\/8244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/comments?post=8244"}],"version-history":[{"count":2,"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/pages\/8244\/revisions"}],"predecessor-version":[{"id":8249,"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/pages\/8244\/revisions\/8249"}],"up":[{"embeddable":true,"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/pages\/1425"}],"wp:attachment":[{"href":"https:\/\/tintenwolf.mrkeks.net\/en\/wp-json\/wp\/v2\/media?parent=8244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}